{"id":688,"date":"2015-06-17T09:21:09","date_gmt":"2015-06-17T08:21:09","guid":{"rendered":"http:\/\/lynx-medias.fr\/site\/?p=688"},"modified":"2015-06-17T09:45:55","modified_gmt":"2015-06-17T08:45:55","slug":"enquete-participative-anc","status":"publish","type":"post","link":"http:\/\/lynx-medias.fr\/site\/enquete-participative-anc\/","title":{"rendered":"Des associations lancent une enqu\u00eate participative sur l&rsquo;ANC"},"content":{"rendered":"<h4>Deux associations, <a href=\"http:\/\/www.france-libertes.org\/\">France Libert\u00e9s<\/a> et <a href=\"http:\/\/reseauconfiance.org\/\">Confi-ANC-e<\/a>, et le magazine <a href=\"http:\/\/www.60millions-mag.com\/\">60 millions de consommateurs<\/a> lancent une enqu\u00eate participative sur les services publics d&rsquo;assainissement non collectif (spanc).<\/h4>\n<h4>In\u00e9galit\u00e9 des services<\/h4>\n<p>Ces services publics, qui auraient d\u00fb \u00eatre mis en place par toutes les collectivit\u00e9s et avoir contr\u00f4l\u00e9 toutes les installations existantes d&rsquo;assainissement non collectif (ANC) au 31 d\u00e9cembre 2012, ne couvrent pas encore tout le territoire. Certains sont communaux, d&rsquo;autres intercommunaux, d&rsquo;autres d\u00e9partementaux. Certains ont d\u00e9l\u00e9gu\u00e9 le contr\u00f4le \u00e0 des entreprises priv\u00e9es (parmi lesquelles les trois grands de l&rsquo;eau, Saur, Veolia et Suez), d&rsquo;autres l&rsquo;assurent en r\u00e9gie. L&rsquo;objectif affich\u00e9 de ces contr\u00f4les est de r\u00e9duire les pollutions diffuses. Les travaux de r\u00e9habilitation d&rsquo;un syst\u00e8me d&rsquo;\u00e9puration ne doivent normalement \u00eatre rendus obligatoires que lorsque l&rsquo;installation pose un danger pour l&rsquo;environnement ou la sant\u00e9, ou lors d&rsquo;une vente. Selon les trois partenaires, la loi aurait cependant \u00e9t\u00e9 mise en place surtout pour g\u00e9n\u00e9rer un nouveau secteur d&rsquo;activit\u00e9 \u00e9conomique, et les spanc prescriraient parfois des travaux \u00ab\u00a0qui vont au-del\u00e0 du raisonnable\u00a0\u00bb, selon Thomas Laurenceau, r\u00e9dacteur en chef de 60 millions de consommateurs.<\/p>\n<h4><a href=\"http:\/\/lynx-medias.fr\/site\/wp-content\/uploads\/2015\/06\/Euro_coins_and_banknotes.jpg\"><img loading=\"lazy\" class=\"alignleft size-full wp-image-710\" src=\"http:\/\/lynx-medias.fr\/site\/wp-content\/uploads\/2015\/06\/Euro_coins_and_banknotes.jpg\" alt=\"billets et pi\u00e8ces\" width=\"256\" height=\"192\" data-id=\"710\" \/><\/a><\/h4>\n<h4>In\u00e9galit\u00e9 des co\u00fbts<\/h4>\n<p>Les trois partenaires constatent une in\u00e9galit\u00e9 des prix des contr\u00f4les d&rsquo;un spanc \u00e0 l&rsquo;autre, \u00ab\u00a0dont le diff\u00e9rentiel peut aller de un \u00e0 quinze\u00a0\u00bb, estime Claude Reveillault, pr\u00e9sidente de la conf\u00e9d\u00e9ration Confi-ANC-e. Les associations s&rsquo;insurgent aussi contre le fait qu&rsquo;il n&rsquo;y ait pas de r\u00e9f\u00e9rentiel de formation pour les agents charg\u00e9s du contr\u00f4le, \u00ab\u00a0alors que c&rsquo;est le seul contr\u00f4le qui entra\u00eene des travaux obligatoires\u00a0\u00bb, dont le montant est parfois tr\u00e8s \u00e9lev\u00e9, explique Thomas Laurenceau.<\/p>\n<h4>\u00a0Enqu\u00eate en ligne<\/h4>\n<p>Ils demandent tout d&rsquo;abord aux particuliers de remplir une enqu\u00eate en ligne, accessible sur leur sites respectifs ou <a href=\"http:\/\/vip.sphinxonline.net\/inc60\/spanc-opetransparence\/questionnaire.htm\" target=\"_blank\">ici<\/a>.<br \/>\nL&rsquo;enqu\u00eate peut \u00eatre remplie en une dizaine de minutes. Les particuliers sont invit\u00e9s \u00e0 indiquer le nom de leur Spanc et \u00e9ventuellement du d\u00e9l\u00e9gataire charg\u00e9 des contr\u00f4les, le montant des redevances, si des services compl\u00e9mentaires sont propos\u00e9s apr\u00e8s le contr\u00f4le&#8230; Il leur est aussi demand\u00e9 s&rsquo;ils sont satisfaits du service\u00a0; ils peuvent ici faire des commentaires.<\/p>\n<h4>R\u00e8glement de service<\/h4>\n<p>D&rsquo;autre part, les associations demandent au public de leur faire parvenir, par mail ou par courrier postal, le r\u00e8glement de service du spanc de leur collectivit\u00e9.<br \/>\n\u00ab\u00a0Nous ne sommes pas contre l&rsquo;id\u00e9e d&rsquo;un service public pour contr\u00f4ler les installations d&rsquo;assainissement non collectif (ANC). Mais ce service est mal parti, et il est temps de remettre les choses dans le sens de la marche\u00a0\u00bb. Emmanuel Poilane, directeur g\u00e9n\u00e9ral de France Libert\u00e9s.<\/p>\n<div class=\"sondage\">\n<div id=\"encadre\" class=\"eau\">\n<h4>Petit jeu\u00a0: quelques chiffres sur l&rsquo;ANC<\/h4>\n<form><b><u>Combien d&rsquo;habitations sont en assainissement non collectif ?<\/u><\/b><br \/>\n<input id=\"2millions\" name=\"question1\" type=\"radio\" value=\"2 millions, soit environ 10% de la population.\" \/> <label for=\"2millions\">2 millions, soit environ 10% de la population<\/label><\/p>\n<p><input id=\"4millions\" name=\"question1\" type=\"radio\" value=\"4 \u00e0 5 millions, soit environ 20% de la population.\" \/> <label for=\"4millions\">4 \u00e0 5 millions, soit environ 20% de la population<\/label><\/p>\n<p><input id=\"10millions\" name=\"question1\" type=\"radio\" value=\"10 millions, soit environ 10% de la population.\" \/> <label for=\"10millions\">10 millions, soit environ 40% de la population<\/label><\/p>\n<p><b><u>Les pollutions li\u00e9es par l\u2019assainissement non collectif repr\u00e9sentent<\/u><\/b><br \/>\n<input id=\"5%\" name=\"question2\" type=\"radio\" value=\"environ 5 % des pressions polluantes au niveau national.\" \/> <label for=\"5%\">environ 5 % des pressions polluantes au niveau national<\/label><\/p>\n<p><input id=\"15%\" name=\"question2\" type=\"radio\" value=\"environ 15 % des pressions polluantes au niveau national.\" \/> <label for=\"15%\">environ 15 % des pressions polluantes au niveau national<\/label><\/p>\n<p><input id=\"35%\" name=\"question2\" type=\"radio\" value=\"environ 35 % des pressions polluantes au niveau national.\" \/> <label for=\"35%\">environ 35 % des pressions polluantes au niveau national<\/label><\/p>\n<p><b><u>Une installation d\u2019assainissement non collectif co\u00fbte en moyenne<\/u><\/b><br \/>\n<input id=\"3000\" name=\"question3\" type=\"radio\" value=\"entre 3 000 et 4 000 euros\" \/> <label for=\"3000\">entre 3 000 et 4 000 euros<\/label><\/p>\n<p><input id=\"8000\" name=\"question3\" type=\"radio\" value=\"entre 4 000 et 8 000 euros\" \/> <label for=\"8000\">entre 4 000 et 8 000 euros<\/label><\/p>\n<p><input id=\"10000\" name=\"question3\" type=\"radio\" value=\"entre 8 000 et 10 000 euros\" \/> <label for=\"10000\">entre 8 000 et 10 000 euros<\/label><\/p>\n<p>Les r\u00e9ponses sont <a href=\"http:\/\/lynx-medias.fr\/site\/?p=726\">\u00e0 retrouver ici<\/a><\/p>\n<p><a href=\"http:\/\/www.developpement-durable.gouv.fr\/L-assainissement-non-collectif.html\"> Pour en savoir plus: le site du minist\u00e8re de l&rsquo;Ecologie<\/a><\/p>\n<\/form>\n<\/div>\n<\/div>\n<p>Illustration: A\u00efna Collin\/METL-MEDD<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deux associations, France Libert\u00e9s et Confi-ANC-e, et le magazine 60 millions de consommateurs lancent une enqu\u00eate participative sur les services publics d&rsquo;assainissement non collectif (spanc). In\u00e9galit\u00e9 des services Ces services publics, qui auraient d\u00fb \u00eatre mis en place par toutes les collectivit\u00e9s et avoir contr\u00f4l\u00e9 toutes les installations existantes d&rsquo;assainissement non collectif (ANC) au 31 d\u00e9cembre 2012, ne couvrent pas encore tout le territoire. Certains sont communaux, d&rsquo;autres intercommunaux, d&rsquo;autres d\u00e9partementaux. Certains ont d\u00e9l\u00e9gu\u00e9 le contr\u00f4le \u00e0 des entreprises priv\u00e9es (parmi lesquelles les trois grands de l&rsquo;eau, Saur, Veolia et Suez), d&rsquo;autres l&rsquo;assurent en r\u00e9gie. L&rsquo;objectif affich\u00e9 de ces contr\u00f4les<\/p>\n","protected":false},"author":1,"featured_media":697,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"http:\/\/lynx-medias.fr\/site\/wp-json\/wp\/v2\/posts\/688"}],"collection":[{"href":"http:\/\/lynx-medias.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/lynx-medias.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/lynx-medias.fr\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/lynx-medias.fr\/site\/wp-json\/wp\/v2\/comments?post=688"}],"version-history":[{"count":34,"href":"http:\/\/lynx-medias.fr\/site\/wp-json\/wp\/v2\/posts\/688\/revisions"}],"predecessor-version":[{"id":734,"href":"http:\/\/lynx-medias.fr\/site\/wp-json\/wp\/v2\/posts\/688\/revisions\/734"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/lynx-medias.fr\/site\/wp-json\/wp\/v2\/media\/697"}],"wp:attachment":[{"href":"http:\/\/lynx-medias.fr\/site\/wp-json\/wp\/v2\/media?parent=688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/lynx-medias.fr\/site\/wp-json\/wp\/v2\/categories?post=688"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/lynx-medias.fr\/site\/wp-json\/wp\/v2\/tags?post=688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}